{"id":8910,"date":"2023-11-29T15:02:05","date_gmt":"2023-11-29T20:02:05","guid":{"rendered":"https:\/\/omcabogados.com.pe\/?page_id=8910"},"modified":"2024-01-30T16:35:07","modified_gmt":"2024-01-30T21:35:07","slug":"federico-mevius-pigati","status":"publish","type":"page","link":"https:\/\/omcabogados.com.pe\/es\/abogados-consultores\/federico-mevius-pigati\/","title":{"rendered":"Federico Mevius Pigati"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-page\" data-elementor-id=\"8910\" class=\"elementor elementor-8910\" data-elementor-post-type=\"page\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-367b0fa elementor-section-height-min-height elementor-section-boxed elementor-section-height-default elementor-section-items-middle\" data-id=\"367b0fa\" data-element_type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-7fcffc8\" data-id=\"7fcffc8\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-838189c elementor-widget elementor-widget-heading\" data-id=\"838189c\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h1 class=\"elementor-heading-title elementor-size-default\">Abogados &amp; Consultores<\/h1>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-b90d56a elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"b90d56a\" data-element_type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t\t<div class=\"elementor-background-overlay\"><\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-5478583\" data-id=\"5478583\" data-element_type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-3462ae4 elementor-widget elementor-widget-image\" data-id=\"3462ae4\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" src=\"https:\/\/omcabogados.com.pe\/wp-content\/uploads\/elementor\/thumbs\/Federico-Mevius_sf-qgbc6qnhik3ob4u6zbth78r3kk67is0kf10uw18qd0.png\" title=\"Federico-Mevius_sf\" alt=\"Federico-Mevius_sf\" loading=\"lazy\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-38fe764 elementor-widget-divider--view-line elementor-widget elementor-widget-divider\" data-id=\"38fe764\" data-element_type=\"widget\" data-widget_type=\"divider.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-divider\">\n\t\t\t<span class=\"elementor-divider-separator\">\n\t\t\t\t\t\t<\/span>\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element-custom_font_size elementor-element elementor-element-b6ce02d elementor-widget elementor-widget-text-editor\" data-id=\"b6ce02d\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<p style=\"text-align: center;\">E-mail: <a href=\"mailto:fmevius@omcabogados.com\"><strong>fmevius@omcabogados.com<\/strong><\/a><\/p>\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-fbe757b elementor-shape-circle elementor-grid-0 e-grid-align-center elementor-widget elementor-widget-social-icons\" data-id=\"fbe757b\" data-element_type=\"widget\" data-widget_type=\"social-icons.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-social-icons-wrapper elementor-grid\">\n\t\t\t\t\t\t\t<span class=\"elementor-grid-item\">\n\t\t\t\t\t<a class=\"elementor-icon elementor-social-icon elementor-social-icon-facebook elementor-repeater-item-6ab08c4\" href=\"https:\/\/www.facebook.com\/omcabogados.consultores\/\" target=\"_blank\">\n\t\t\t\t\t\t<span class=\"elementor-screen-only\">Facebook<\/span>\n\t\t\t\t\t\t<i class=\"fab fa-facebook\"><\/i>\t\t\t\t\t<\/a>\n\t\t\t\t<\/span>\n\t\t\t\t\t\t\t<span class=\"elementor-grid-item\">\n\t\t\t\t\t<a class=\"elementor-icon elementor-social-icon elementor-social-icon-instagram elementor-repeater-item-495c46e\" href=\"https:\/\/www.instagram.com\/omcabogadosyconsultores\" target=\"_blank\">\n\t\t\t\t\t\t<span class=\"elementor-screen-only\">Instagram<\/span>\n\t\t\t\t\t\t<i class=\"fab fa-instagram\"><\/i>\t\t\t\t\t<\/a>\n\t\t\t\t<\/span>\n\t\t\t\t\t\t\t<span class=\"elementor-grid-item\">\n\t\t\t\t\t<a class=\"elementor-icon elementor-social-icon elementor-social-icon-linkedin elementor-repeater-item-9920d03\" href=\"https:\/\/www.linkedin.com\/company\/omc-abogados-consultores\/\" target=\"_blank\">\n\t\t\t\t\t\t<span class=\"elementor-screen-only\">Linkedin<\/span>\n\t\t\t\t\t\t<i class=\"fab fa-linkedin\"><\/i>\t\t\t\t\t<\/a>\n\t\t\t\t<\/span>\n\t\t\t\t\t\t\t<span class=\"elementor-grid-item\">\n\t\t\t\t\t<a class=\"elementor-icon elementor-social-icon elementor-social-icon-twitter elementor-repeater-item-c73e6b4\" href=\"https:\/\/twitter.com\/omcabogadosperu\" target=\"_blank\">\n\t\t\t\t\t\t<span class=\"elementor-screen-only\">Twitter<\/span>\n\t\t\t\t\t\t<i class=\"fab fa-twitter\"><\/i>\t\t\t\t\t<\/a>\n\t\t\t\t<\/span>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-37d8953\" data-id=\"37d8953\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-73644b8 elementor-widget elementor-widget-heading\" data-id=\"73644b8\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Federico Mevius Pigati<\/h2>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-35afdad elementor-widget-divider--view-line elementor-widget elementor-widget-divider\" data-id=\"35afdad\" data-element_type=\"widget\" data-widget_type=\"divider.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-divider\">\n\t\t\t<span class=\"elementor-divider-separator\">\n\t\t\t\t\t\t<\/span>\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-8926919 elementor-widget elementor-widget-heading\" data-id=\"8926919\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h4 class=\"elementor-heading-title elementor-size-default\">\u00c1REAS DE ESPECIALIZACI\u00d3N<\/h4>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element-custom_font_size elementor-element elementor-element-308315f elementor-widget elementor-widget-text-editor\" data-id=\"308315f\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<p style=\"text-align: center;\">Derecho corporativo.<br \/>Derecho laboral.<br \/>Propiedad intelectual.<br \/>Licitaciones y ofertas p\u00fablicas.<\/p>\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-2f1097a elementor-widget-divider--view-line elementor-widget elementor-widget-divider\" data-id=\"2f1097a\" data-element_type=\"widget\" data-widget_type=\"divider.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-divider\">\n\t\t\t<span class=\"elementor-divider-separator\">\n\t\t\t\t\t\t<\/span>\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-384eda0 elementor-widget elementor-widget-heading\" data-id=\"384eda0\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h4 class=\"elementor-heading-title elementor-size-default\">IDIOMAS<\/h4>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element-custom_font_size elementor-element elementor-element-cb8d2ba elementor-widget elementor-widget-text-editor\" data-id=\"cb8d2ba\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<p style=\"text-align: center;\">Espa\u00f1ol<br \/>Ingl\u00e9s<\/p>\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-ac01a52 elementor-hidden-desktop elementor-hidden-tablet elementor-hidden-mobile elementor-widget-divider--view-line elementor-widget elementor-widget-divider\" data-id=\"ac01a52\" data-element_type=\"widget\" data-widget_type=\"divider.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-divider\">\n\t\t\t<span class=\"elementor-divider-separator\">\n\t\t\t\t\t\t<\/span>\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-a29df62 elementor-widget elementor-widget-image\" data-id=\"a29df62\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" src=\"https:\/\/omcabogados.com.pe\/wp-content\/uploads\/elementor\/thumbs\/qr-omc-abogados-qgtp9bzts6il6p9kf16ldtb23tcpq5ft2wo9e9evv4.png\" title=\"qr-omc-abogados\" alt=\"qr-omc-abogados\" loading=\"lazy\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-dfeb865 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"dfeb865\" data-element_type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;gradient&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-7878c0a\" data-id=\"7878c0a\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-a975008 elementor-widget elementor-widget-heading\" data-id=\"a975008\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h4 class=\"elementor-heading-title elementor-size-default\">ABOGADOS &amp; CONSULTORES<\/h4>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-b640468 elementor-widget elementor-widget-visual-portfolio\" data-id=\"b640468\" data-element_type=\"widget\" data-widget_type=\"visual-portfolio.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div\n\t\t\t\t\t>\n\t\t\t\t\t\t\t\n<div class=\"vp-portfolio vp-uid-d2652116 vp-id-9226 \"\n\tdata-vp-layout=\"slider\" data-vp-content-source=\"images\" data-vp-items-style=\"emerge\" data-vp-items-click-action=\"url\" data-vp-items-gap=\"5\" data-vp-items-gap-vertical=\"\" data-vp-pagination=\"load-more\" data-vp-next-page-url=\"\" data-vp-slider-effect=\"slide\" data-vp-slider-items-height=\"auto\" data-vp-slider-slides-per-view=\"4\" data-vp-slider-speed=\"0.3\" data-vp-slider-autoplay=\"3\" data-vp-slider-autoplay-hover-pause=\"true\" data-vp-slider-centered-slides=\"false\" data-vp-slider-loop=\"false\" data-vp-slider-free-mode=\"false\" data-vp-slider-free-mode-sticky=\"false\" data-vp-slider-arrows=\"false\" data-vp-slider-bullets=\"false\" data-vp-slider-bullets-dynamic=\"false\" data-vp-slider-mousewheel=\"false\" data-vp-slider-thumbnails=\"false\" >\n\t<div class=\"vp-portfolio__preloader-wrap\">\n\t\t<div class=\"vp-portfolio__preloader\">\n\t\t\t<img decoding=\"async\" loading=\"eager\" src=\"https:\/\/omcabogados.com.pe\/wp-content\/plugins\/visual-portfolio-pro\/core-plugin\/assets\/images\/logo-dark.svg\" alt=\"Visual Portfolio, Posts &amp; Image Gallery for WordPress\" width=\"20\" height=\"20\" data-skip-lazy>\n\t\t<\/div>\n\t<\/div>\n\t\t<div class=\"vp-portfolio__items-wrap\">\n\t\t\t\n<div class=\"vp-portfolio__items vp-portfolio__items-style-emerge vp-portfolio__items-show-overlay-hover vp-portfolio__items-show-caption-hover\">\n\n\t\t<div\t\tclass=\"vp-portfolio__item-wrap vp-portfolio__item-uid-01520486\" data-vp-filter=\"\" \t\t>\n\t\t\t\t\t\t\t\t\t<figure class=\"vp-portfolio__item\">\n\t\t\t\t\n<div class=\"vp-portfolio__item-img-wrap\">\n\t<div class=\"vp-portfolio__item-img\">\n\t\t\t<a\n\t\thref=\"https:\/\/omcabogados.com.pe\/abogados-consultores\/oscar-mago-carranza\/\"\n\t\t\t>\n\t\n\t\t<noscript><img fetchpriority=\"high\" decoding=\"async\" width=\"480\" height=\"480\" data-skip-lazy src=\"https:\/\/omcabogados.com.pe\/wp-content\/uploads\/Oscar-Mago_sf.png\" class=\"wp-image-16616\" alt=\"\" \/><\/noscript><img decoding=\"async\" width=\"480\" height=\"480\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iNDgwIiBoZWlnaHQ9IjQ4MCIgdmlld0JveD0iMCAwIDQ4MCA0ODAiIGZpbGw9Im5vbmUiIHhtbG5zPSJodHRwOi8vd3d3LnczLm9yZy8yMDAwL3N2ZyI+PC9zdmc+\" class=\"wp-image-16616 vp-lazyload\" alt data-src=\"https:\/\/omcabogados.com.pe\/wp-content\/uploads\/Oscar-Mago_sf.png\" data-sizes=\"auto\" loading=\"eager\">\n\t\t<div class=\"vp-portfolio__item-overlay\"><\/div>\n\n\t\t<\/a>\t<\/div>\n<\/div>\n\n\t<figcaption class=\"vp-portfolio__item-caption vp-portfolio__item-caption-text-align-center\">\n\t\t<div class=\"vp-portfolio__item-meta-wrap vp-portfolio__custom-scrollbar\">\n\t\t\t<div class=\"vp-portfolio__item-meta\">\n\t\t\t\t\n<h3 class=\"vp-portfolio__item-meta-title\">\n\t\t<a\n\t\thref=\"https:\/\/omcabogados.com.pe\/abogados-consultores\/oscar-mago-carranza\/\"\n\t\t\t>\n\tOscar Mago Carranza<\/a><\/h3>\n\n<div class=\"vp-portfolio__item-meta-excerpt\">\n\t<div>\n\t\tomago@omcabogados.com.pe\t<\/div>\n<\/div>\n\t\t\t<\/div>\n\t\t<\/div>\n\t<\/figcaption>\n\t\t\t<\/figure>\n\t\t\t\t\t<\/div>\n\t\t\n\t\t<div\t\tclass=\"vp-portfolio__item-wrap vp-portfolio__item-uid-63ba04d0\" data-vp-filter=\"\" \t\t>\n\t\t\t\t\t\t\t\t\t<figure class=\"vp-portfolio__item\">\n\t\t\t\t\n<div class=\"vp-portfolio__item-img-wrap\">\n\t<div class=\"vp-portfolio__item-img\">\n\t\t\t<a\n\t\thref=\"https:\/\/omcabogados.com.pe\/abogados-consultores\/juan-carlos-diaz-iglesias\/\"\n\t\t\t>\n\t\n\t\t<noscript><img decoding=\"async\" width=\"480\" height=\"480\" data-skip-lazy src=\"https:\/\/omcabogados.com.pe\/wp-content\/uploads\/Juan-Carlos-Diaz_sf.png\" class=\"wp-image-9096\" alt=\"\" \/><\/noscript><img decoding=\"async\" width=\"480\" height=\"480\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iNDgwIiBoZWlnaHQ9IjQ4MCIgdmlld0JveD0iMCAwIDQ4MCA0ODAiIGZpbGw9Im5vbmUiIHhtbG5zPSJodHRwOi8vd3d3LnczLm9yZy8yMDAwL3N2ZyI+PC9zdmc+\" class=\"wp-image-9096 vp-lazyload\" alt data-src=\"https:\/\/omcabogados.com.pe\/wp-content\/uploads\/Juan-Carlos-Diaz_sf.png\" data-sizes=\"auto\" loading=\"eager\">\n\t\t<div class=\"vp-portfolio__item-overlay\"><\/div>\n\n\t\t<\/a>\t<\/div>\n<\/div>\n\n\t<figcaption class=\"vp-portfolio__item-caption vp-portfolio__item-caption-text-align-center\">\n\t\t<div class=\"vp-portfolio__item-meta-wrap vp-portfolio__custom-scrollbar\">\n\t\t\t<div class=\"vp-portfolio__item-meta\">\n\t\t\t\t\n<h3 class=\"vp-portfolio__item-meta-title\">\n\t\t<a\n\t\thref=\"https:\/\/omcabogados.com.pe\/abogados-consultores\/juan-carlos-diaz-iglesias\/\"\n\t\t\t>\n\tJuan Carlos D\u00edaz<\/a><\/h3>\n\n<div class=\"vp-portfolio__item-meta-excerpt\">\n\t<div>\n\t\tjcdiaz@omcabogados.com\t<\/div>\n<\/div>\n\t\t\t<\/div>\n\t\t<\/div>\n\t<\/figcaption>\n\t\t\t<\/figure>\n\t\t\t\t\t<\/div>\n\t\t\n\t\t<div\t\tclass=\"vp-portfolio__item-wrap vp-portfolio__item-uid-531d4e96\" data-vp-filter=\"\" \t\t>\n\t\t\t\t\t\t\t\t\t<figure class=\"vp-portfolio__item\">\n\t\t\t\t\n<div class=\"vp-portfolio__item-img-wrap\">\n\t<div class=\"vp-portfolio__item-img\">\n\t\t\t<a\n\t\thref=\"https:\/\/omcabogados.com.pe\/es\/abogados-consultores\/luis-maura-moscoco\/\"\n\t\t\t>\n\t\n\t\t<noscript><img decoding=\"async\" width=\"480\" height=\"480\" data-skip-lazy src=\"https:\/\/omcabogados.com.pe\/wp-content\/uploads\/Luis-Maura_sf.png\" class=\"wp-image-9097\" alt=\"\" \/><\/noscript><img decoding=\"async\" width=\"480\" height=\"480\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iNDgwIiBoZWlnaHQ9IjQ4MCIgdmlld0JveD0iMCAwIDQ4MCA0ODAiIGZpbGw9Im5vbmUiIHhtbG5zPSJodHRwOi8vd3d3LnczLm9yZy8yMDAwL3N2ZyI+PC9zdmc+\" class=\"wp-image-9097 vp-lazyload\" alt data-src=\"https:\/\/omcabogados.com.pe\/wp-content\/uploads\/Luis-Maura_sf.png\" data-sizes=\"auto\" loading=\"eager\">\n\t\t<div class=\"vp-portfolio__item-overlay\"><\/div>\n\n\t\t<\/a>\t<\/div>\n<\/div>\n\n\t<figcaption class=\"vp-portfolio__item-caption vp-portfolio__item-caption-text-align-center\">\n\t\t<div class=\"vp-portfolio__item-meta-wrap vp-portfolio__custom-scrollbar\">\n\t\t\t<div class=\"vp-portfolio__item-meta\">\n\t\t\t\t\n<h3 class=\"vp-portfolio__item-meta-title\">\n\t\t<a\n\t\thref=\"https:\/\/omcabogados.com.pe\/es\/abogados-consultores\/luis-maura-moscoco\/\"\n\t\t\t>\n\tLuis Maura<\/a><\/h3>\n\n<div class=\"vp-portfolio__item-meta-excerpt\">\n\t<div>\n\t\tlmaura@omcabogados.com\t<\/div>\n<\/div>\n\t\t\t<\/div>\n\t\t<\/div>\n\t<\/figcaption>\n\t\t\t<\/figure>\n\t\t\t\t\t<\/div>\n\t\t\n\t\t<div\t\tclass=\"vp-portfolio__item-wrap vp-portfolio__item-uid-fec27ab7\" data-vp-filter=\"\" \t\t>\n\t\t\t\t\t\t\t\t\t<figure class=\"vp-portfolio__item\">\n\t\t\t\t\n<div class=\"vp-portfolio__item-img-wrap\">\n\t<div class=\"vp-portfolio__item-img\">\n\t\t\t<a\n\t\thref=\"https:\/\/omcabogados.com.pe\/abogados-consultores\/federico-mevius-pigati\/\"\n\t\t\t>\n\t\n\t\t<noscript><img loading=\"lazy\" decoding=\"async\" width=\"480\" height=\"480\" data-skip-lazy src=\"https:\/\/omcabogados.com.pe\/wp-content\/uploads\/Federico-Mevius_sf.png\" class=\"wp-image-9098\" alt=\"\" \/><\/noscript><img decoding=\"async\" width=\"480\" height=\"480\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iNDgwIiBoZWlnaHQ9IjQ4MCIgdmlld0JveD0iMCAwIDQ4MCA0ODAiIGZpbGw9Im5vbmUiIHhtbG5zPSJodHRwOi8vd3d3LnczLm9yZy8yMDAwL3N2ZyI+PC9zdmc+\" class=\"wp-image-9098 vp-lazyload\" alt data-src=\"https:\/\/omcabogados.com.pe\/wp-content\/uploads\/Federico-Mevius_sf.png\" data-sizes=\"auto\" loading=\"eager\">\n\t\t<div class=\"vp-portfolio__item-overlay\"><\/div>\n\n\t\t<\/a>\t<\/div>\n<\/div>\n\n\t<figcaption class=\"vp-portfolio__item-caption vp-portfolio__item-caption-text-align-center\">\n\t\t<div class=\"vp-portfolio__item-meta-wrap vp-portfolio__custom-scrollbar\">\n\t\t\t<div class=\"vp-portfolio__item-meta\">\n\t\t\t\t\n<h3 class=\"vp-portfolio__item-meta-title\">\n\t\t<a\n\t\thref=\"https:\/\/omcabogados.com.pe\/abogados-consultores\/federico-mevius-pigati\/\"\n\t\t\t>\n\tFederico Mevius<\/a><\/h3>\n\n<div class=\"vp-portfolio__item-meta-excerpt\">\n\t<div>\n\t\tfmevius@omcabogados.com\t<\/div>\n<\/div>\n\t\t\t<\/div>\n\t\t<\/div>\n\t<\/figcaption>\n\t\t\t<\/figure>\n\t\t\t\t\t<\/div>\n\t\t\n\t\t<div\t\tclass=\"vp-portfolio__item-wrap vp-portfolio__item-uid-3be59631\" data-vp-filter=\"\" \t\t>\n\t\t\t\t\t\t\t\t\t<figure class=\"vp-portfolio__item\">\n\t\t\t\t\n<div class=\"vp-portfolio__item-img-wrap\">\n\t<div class=\"vp-portfolio__item-img\">\n\t\t\t<a\n\t\thref=\"https:\/\/omcabogados.com.pe\/abogados-consultores\/lorena-moya\/\"\n\t\t\t>\n\t\n\t\t<noscript><img loading=\"lazy\" decoding=\"async\" width=\"480\" height=\"480\" data-skip-lazy src=\"https:\/\/omcabogados.com.pe\/wp-content\/uploads\/Lorena-Moya_sf.png\" class=\"wp-image-9099\" alt=\"\" \/><\/noscript><img decoding=\"async\" width=\"480\" height=\"480\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iNDgwIiBoZWlnaHQ9IjQ4MCIgdmlld0JveD0iMCAwIDQ4MCA0ODAiIGZpbGw9Im5vbmUiIHhtbG5zPSJodHRwOi8vd3d3LnczLm9yZy8yMDAwL3N2ZyI+PC9zdmc+\" class=\"wp-image-9099 vp-lazyload\" alt data-src=\"https:\/\/omcabogados.com.pe\/wp-content\/uploads\/Lorena-Moya_sf.png\" data-sizes=\"auto\" loading=\"eager\">\n\t\t<div class=\"vp-portfolio__item-overlay\"><\/div>\n\n\t\t<\/a>\t<\/div>\n<\/div>\n\n\t<figcaption class=\"vp-portfolio__item-caption vp-portfolio__item-caption-text-align-center\">\n\t\t<div class=\"vp-portfolio__item-meta-wrap vp-portfolio__custom-scrollbar\">\n\t\t\t<div class=\"vp-portfolio__item-meta\">\n\t\t\t\t\n<h3 class=\"vp-portfolio__item-meta-title\">\n\t\t<a\n\t\thref=\"https:\/\/omcabogados.com.pe\/abogados-consultores\/lorena-moya\/\"\n\t\t\t>\n\tLorena Moya<\/a><\/h3>\n\n<div class=\"vp-portfolio__item-meta-excerpt\">\n\t<div>\n\t\tlmoya@omcabogados.com.pe\t<\/div>\n<\/div>\n\t\t\t<\/div>\n\t\t<\/div>\n\t<\/figcaption>\n\t\t\t<\/figure>\n\t\t\t\t\t<\/div>\n\t\t\n\t\t<div\t\tclass=\"vp-portfolio__item-wrap vp-portfolio__item-uid-af59d65b\" data-vp-filter=\"\" \t\t>\n\t\t\t\t\t\t\t\t\t<figure class=\"vp-portfolio__item\">\n\t\t\t\t\n<div class=\"vp-portfolio__item-img-wrap\">\n\t<div class=\"vp-portfolio__item-img\">\n\t\t\t<a\n\t\thref=\"https:\/\/omcabogados.com.pe\/abogados-consultores\/fernando-santivanez-yuli\/\"\n\t\t\t>\n\t\n\t\t<noscript><img loading=\"lazy\" decoding=\"async\" width=\"480\" height=\"480\" data-skip-lazy src=\"https:\/\/omcabogados.com.pe\/wp-content\/uploads\/Fernando-Santivanez_sf.png\" class=\"wp-image-9100\" alt=\"\" \/><\/noscript><img decoding=\"async\" width=\"480\" height=\"480\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iNDgwIiBoZWlnaHQ9IjQ4MCIgdmlld0JveD0iMCAwIDQ4MCA0ODAiIGZpbGw9Im5vbmUiIHhtbG5zPSJodHRwOi8vd3d3LnczLm9yZy8yMDAwL3N2ZyI+PC9zdmc+\" class=\"wp-image-9100 vp-lazyload\" alt data-src=\"https:\/\/omcabogados.com.pe\/wp-content\/uploads\/Fernando-Santivanez_sf.png\" data-sizes=\"auto\" loading=\"eager\">\n\t\t<div class=\"vp-portfolio__item-overlay\"><\/div>\n\n\t\t<\/a>\t<\/div>\n<\/div>\n\n\t<figcaption class=\"vp-portfolio__item-caption vp-portfolio__item-caption-text-align-center\">\n\t\t<div class=\"vp-portfolio__item-meta-wrap vp-portfolio__custom-scrollbar\">\n\t\t\t<div class=\"vp-portfolio__item-meta\">\n\t\t\t\t\n<h3 class=\"vp-portfolio__item-meta-title\">\n\t\t<a\n\t\thref=\"https:\/\/omcabogados.com.pe\/abogados-consultores\/fernando-santivanez-yuli\/\"\n\t\t\t>\n\tFernando Santiva\u00f1ez<\/a><\/h3>\n\n<div class=\"vp-portfolio__item-meta-excerpt\">\n\t<div>\n\t\tfsantivanez@omcabogados.com\t<\/div>\n<\/div>\n\t\t\t<\/div>\n\t\t<\/div>\n\t<\/figcaption>\n\t\t\t<\/figure>\n\t\t\t\t\t<\/div>\n\t\t\n\t\t<div\t\tclass=\"vp-portfolio__item-wrap vp-portfolio__item-uid-06f7cda7\" data-vp-filter=\"\" \t\t>\n\t\t\t\t\t\t\t\t\t<figure class=\"vp-portfolio__item\">\n\t\t\t\t\n<div class=\"vp-portfolio__item-img-wrap\">\n\t<div class=\"vp-portfolio__item-img\">\n\t\t\t<a\n\t\thref=\"https:\/\/omcabogados.com.pe\/abogados-consultores\/fernando-de-taboada\/\"\n\t\t\t>\n\t\n\t\t<noscript><img loading=\"lazy\" decoding=\"async\" width=\"480\" height=\"480\" data-skip-lazy src=\"https:\/\/omcabogados.com.pe\/wp-content\/uploads\/Fernando-de-Taoada_sf.png\" class=\"wp-image-9102\" alt=\"\" \/><\/noscript><img decoding=\"async\" width=\"480\" height=\"480\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iNDgwIiBoZWlnaHQ9IjQ4MCIgdmlld0JveD0iMCAwIDQ4MCA0ODAiIGZpbGw9Im5vbmUiIHhtbG5zPSJodHRwOi8vd3d3LnczLm9yZy8yMDAwL3N2ZyI+PC9zdmc+\" class=\"wp-image-9102 vp-lazyload\" alt data-src=\"https:\/\/omcabogados.com.pe\/wp-content\/uploads\/Fernando-de-Taoada_sf.png\" data-sizes=\"auto\" loading=\"eager\">\n\t\t<div class=\"vp-portfolio__item-overlay\"><\/div>\n\n\t\t<\/a>\t<\/div>\n<\/div>\n\n\t<figcaption class=\"vp-portfolio__item-caption vp-portfolio__item-caption-text-align-center\">\n\t\t<div class=\"vp-portfolio__item-meta-wrap vp-portfolio__custom-scrollbar\">\n\t\t\t<div class=\"vp-portfolio__item-meta\">\n\t\t\t\t\n<h3 class=\"vp-portfolio__item-meta-title\">\n\t\t<a\n\t\thref=\"https:\/\/omcabogados.com.pe\/abogados-consultores\/fernando-de-taboada\/\"\n\t\t\t>\n\tFernando de Taboada<\/a><\/h3>\n\n<div class=\"vp-portfolio__item-meta-excerpt\">\n\t<div>\n\t\tfdetaboada@omcabogados.com\t<\/div>\n<\/div>\n\t\t\t<\/div>\n\t\t<\/div>\n\t<\/figcaption>\n\t\t\t<\/figure>\n\t\t\t\t\t<\/div>\n\t\t\n\t\t<div\t\tclass=\"vp-portfolio__item-wrap vp-portfolio__item-uid-4c90d481\" data-vp-filter=\"\" \t\t>\n\t\t\t\t\t\t\t\t\t<figure class=\"vp-portfolio__item\">\n\t\t\t\t\n<div class=\"vp-portfolio__item-img-wrap\">\n\t<div class=\"vp-portfolio__item-img\">\n\t\t\t<a\n\t\thref=\"https:\/\/omcabogados.com.pe\/abogados-y-consultores\/kelly-sanchez-albitres\/\"\n\t\t\t>\n\t\n\t\t<noscript><img loading=\"lazy\" decoding=\"async\" width=\"480\" height=\"480\" data-skip-lazy src=\"https:\/\/omcabogados.com.pe\/wp-content\/uploads\/Kelly-Sanchez_sf.png\" class=\"wp-image-9103\" alt=\"\" \/><\/noscript><img decoding=\"async\" width=\"480\" height=\"480\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iNDgwIiBoZWlnaHQ9IjQ4MCIgdmlld0JveD0iMCAwIDQ4MCA0ODAiIGZpbGw9Im5vbmUiIHhtbG5zPSJodHRwOi8vd3d3LnczLm9yZy8yMDAwL3N2ZyI+PC9zdmc+\" class=\"wp-image-9103 vp-lazyload\" alt data-src=\"https:\/\/omcabogados.com.pe\/wp-content\/uploads\/Kelly-Sanchez_sf.png\" data-sizes=\"auto\" loading=\"eager\">\n\t\t<div class=\"vp-portfolio__item-overlay\"><\/div>\n\n\t\t<\/a>\t<\/div>\n<\/div>\n\n\t<figcaption class=\"vp-portfolio__item-caption vp-portfolio__item-caption-text-align-center\">\n\t\t<div class=\"vp-portfolio__item-meta-wrap vp-portfolio__custom-scrollbar\">\n\t\t\t<div class=\"vp-portfolio__item-meta\">\n\t\t\t\t\n<h3 class=\"vp-portfolio__item-meta-title\">\n\t\t<a\n\t\thref=\"https:\/\/omcabogados.com.pe\/abogados-y-consultores\/kelly-sanchez-albitres\/\"\n\t\t\t>\n\tKelly Sanchez<\/a><\/h3>\n\n<div class=\"vp-portfolio__item-meta-excerpt\">\n\t<div>\n\t\tabogados6@omcabogados.com\t<\/div>\n<\/div>\n\t\t\t<\/div>\n\t\t<\/div>\n\t<\/figcaption>\n\t\t\t<\/figure>\n\t\t\t\t\t<\/div>\n\t\t\n\t\t<div\t\tclass=\"vp-portfolio__item-wrap vp-portfolio__item-uid-50a4d6f3\" data-vp-filter=\"\" \t\t>\n\t\t\t\t\t\t\t\t\t<figure class=\"vp-portfolio__item\">\n\t\t\t\t\n<div class=\"vp-portfolio__item-img-wrap\">\n\t<div class=\"vp-portfolio__item-img\">\n\t\t\t<a\n\t\thref=\"https:\/\/omcabogados.com.pe\/abogados-consultores\/marietta-flores-oyola\/\"\n\t\t\t>\n\t\n\t\t<noscript><img loading=\"lazy\" decoding=\"async\" width=\"480\" height=\"480\" data-skip-lazy src=\"https:\/\/omcabogados.com.pe\/wp-content\/uploads\/Marietta-Flores_sf.png\" class=\"wp-image-9104\" alt=\"\" \/><\/noscript><img decoding=\"async\" width=\"480\" height=\"480\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iNDgwIiBoZWlnaHQ9IjQ4MCIgdmlld0JveD0iMCAwIDQ4MCA0ODAiIGZpbGw9Im5vbmUiIHhtbG5zPSJodHRwOi8vd3d3LnczLm9yZy8yMDAwL3N2ZyI+PC9zdmc+\" class=\"wp-image-9104 vp-lazyload\" alt data-src=\"https:\/\/omcabogados.com.pe\/wp-content\/uploads\/Marietta-Flores_sf.png\" data-sizes=\"auto\" loading=\"eager\">\n\t\t<div class=\"vp-portfolio__item-overlay\"><\/div>\n\n\t\t<\/a>\t<\/div>\n<\/div>\n\n\t<figcaption class=\"vp-portfolio__item-caption vp-portfolio__item-caption-text-align-center\">\n\t\t<div class=\"vp-portfolio__item-meta-wrap vp-portfolio__custom-scrollbar\">\n\t\t\t<div class=\"vp-portfolio__item-meta\">\n\t\t\t\t\n<h3 class=\"vp-portfolio__item-meta-title\">\n\t\t<a\n\t\thref=\"https:\/\/omcabogados.com.pe\/abogados-consultores\/marietta-flores-oyola\/\"\n\t\t\t>\n\tMarietta Flores<\/a><\/h3>\n\n<div class=\"vp-portfolio__item-meta-excerpt\">\n\t<div>\n\t\tabogados2@omcabogados.com\t<\/div>\n<\/div>\n\t\t\t<\/div>\n\t\t<\/div>\n\t<\/figcaption>\n\t\t\t<\/figure>\n\t\t\t\t\t<\/div>\n\t\t\n\t\t<div\t\tclass=\"vp-portfolio__item-wrap vp-portfolio__item-uid-1ac3cfd5\" data-vp-filter=\"\" \t\t>\n\t\t\t\t\t\t\t\t\t<figure class=\"vp-portfolio__item\">\n\t\t\t\t\n<div class=\"vp-portfolio__item-img-wrap\">\n\t<div class=\"vp-portfolio__item-img\">\n\t\t\t<a\n\t\thref=\"https:\/\/omcabogados.com.pe\/abogados-consultores\/evelyn-duenas-morales\/\"\n\t\t\t>\n\t\n\t\t<noscript><img loading=\"lazy\" decoding=\"async\" width=\"480\" height=\"480\" data-skip-lazy src=\"https:\/\/omcabogados.com.pe\/wp-content\/uploads\/Evelyn-Duenas_sf.png\" class=\"wp-image-9105\" alt=\"\" \/><\/noscript><img decoding=\"async\" width=\"480\" height=\"480\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iNDgwIiBoZWlnaHQ9IjQ4MCIgdmlld0JveD0iMCAwIDQ4MCA0ODAiIGZpbGw9Im5vbmUiIHhtbG5zPSJodHRwOi8vd3d3LnczLm9yZy8yMDAwL3N2ZyI+PC9zdmc+\" class=\"wp-image-9105 vp-lazyload\" alt data-src=\"https:\/\/omcabogados.com.pe\/wp-content\/uploads\/Evelyn-Duenas_sf.png\" data-sizes=\"auto\" loading=\"eager\">\n\t\t<div class=\"vp-portfolio__item-overlay\"><\/div>\n\n\t\t<\/a>\t<\/div>\n<\/div>\n\n\t<figcaption class=\"vp-portfolio__item-caption vp-portfolio__item-caption-text-align-center\">\n\t\t<div class=\"vp-portfolio__item-meta-wrap vp-portfolio__custom-scrollbar\">\n\t\t\t<div class=\"vp-portfolio__item-meta\">\n\t\t\t\t\n<h3 class=\"vp-portfolio__item-meta-title\">\n\t\t<a\n\t\thref=\"https:\/\/omcabogados.com.pe\/abogados-consultores\/evelyn-duenas-morales\/\"\n\t\t\t>\n\tEvelyn Due\u00f1as<\/a><\/h3>\n\n<div class=\"vp-portfolio__item-meta-excerpt\">\n\t<div>\n\t\tabogados3@omcabogados.com\t<\/div>\n<\/div>\n\t\t\t<\/div>\n\t\t<\/div>\n\t<\/figcaption>\n\t\t\t<\/figure>\n\t\t\t\t\t<\/div>\n\t\t\n\t\t<div\t\tclass=\"vp-portfolio__item-wrap vp-portfolio__item-uid-7d817856\" data-vp-filter=\"\" \t\t>\n\t\t\t\t\t\t\t\t\t<figure class=\"vp-portfolio__item\">\n\t\t\t\t\n<div class=\"vp-portfolio__item-img-wrap\">\n\t<div class=\"vp-portfolio__item-img\">\n\t\t\t<a\n\t\thref=\"https:\/\/omcabogados.com.pe\/abogados-consultores\/thalia-tapia\/\"\n\t\t\t>\n\t\n\t\t<noscript><img loading=\"lazy\" decoding=\"async\" width=\"480\" height=\"480\" data-skip-lazy src=\"https:\/\/omcabogados.com.pe\/wp-content\/uploads\/thalia-tapia.png\" class=\"wp-image-10186\" alt=\"\" \/><\/noscript><img decoding=\"async\" width=\"480\" height=\"480\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iNDgwIiBoZWlnaHQ9IjQ4MCIgdmlld0JveD0iMCAwIDQ4MCA0ODAiIGZpbGw9Im5vbmUiIHhtbG5zPSJodHRwOi8vd3d3LnczLm9yZy8yMDAwL3N2ZyI+PC9zdmc+\" class=\"wp-image-10186 vp-lazyload\" alt data-src=\"https:\/\/omcabogados.com.pe\/wp-content\/uploads\/thalia-tapia.png\" data-sizes=\"auto\" loading=\"eager\">\n\t\t<div class=\"vp-portfolio__item-overlay\"><\/div>\n\n\t\t<\/a>\t<\/div>\n<\/div>\n\n\t<figcaption class=\"vp-portfolio__item-caption vp-portfolio__item-caption-text-align-center\">\n\t\t<div class=\"vp-portfolio__item-meta-wrap vp-portfolio__custom-scrollbar\">\n\t\t\t<div class=\"vp-portfolio__item-meta\">\n\t\t\t\t\n<h3 class=\"vp-portfolio__item-meta-title\">\n\t\t<a\n\t\thref=\"https:\/\/omcabogados.com.pe\/abogados-consultores\/thalia-tapia\/\"\n\t\t\t>\n\tThalia Tapia<\/a><\/h3>\n\n<div class=\"vp-portfolio__item-meta-excerpt\">\n\t<div>\n\t\tabogados4@omcabogados.com\t<\/div>\n<\/div>\n\t\t\t<\/div>\n\t\t<\/div>\n\t<\/figcaption>\n\t\t\t<\/figure>\n\t\t\t\t\t<\/div>\n\t\t\n\t\t<div\t\tclass=\"vp-portfolio__item-wrap vp-portfolio__item-uid-af597e11\" data-vp-filter=\"\" \t\t>\n\t\t\t\t\t\t\t\t\t<figure class=\"vp-portfolio__item\">\n\t\t\t\t\n<div class=\"vp-portfolio__item-img-wrap\">\n\t<div class=\"vp-portfolio__item-img\">\n\t\t\t<a\n\t\thref=\"https:\/\/omcabogados.com.pe\/abogados-consultores\/ricardo-checa\/\"\n\t\t\t>\n\t\n\t\t<noscript><img loading=\"lazy\" decoding=\"async\" width=\"480\" height=\"480\" data-skip-lazy src=\"https:\/\/omcabogados.com.pe\/wp-content\/uploads\/Ricardo-Checa-Samame-web-1.png\" class=\"wp-image-13434\" alt=\"\" \/><\/noscript><img decoding=\"async\" width=\"480\" height=\"480\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iNDgwIiBoZWlnaHQ9IjQ4MCIgdmlld0JveD0iMCAwIDQ4MCA0ODAiIGZpbGw9Im5vbmUiIHhtbG5zPSJodHRwOi8vd3d3LnczLm9yZy8yMDAwL3N2ZyI+PC9zdmc+\" class=\"wp-image-13434 vp-lazyload\" alt data-src=\"https:\/\/omcabogados.com.pe\/wp-content\/uploads\/Ricardo-Checa-Samame-web-1.png\" data-sizes=\"auto\" loading=\"eager\">\n\t\t<div class=\"vp-portfolio__item-overlay\"><\/div>\n\n\t\t<\/a>\t<\/div>\n<\/div>\n\n\t<figcaption class=\"vp-portfolio__item-caption vp-portfolio__item-caption-text-align-center\">\n\t\t<div class=\"vp-portfolio__item-meta-wrap vp-portfolio__custom-scrollbar\">\n\t\t\t<div class=\"vp-portfolio__item-meta\">\n\t\t\t\t\n<h3 class=\"vp-portfolio__item-meta-title\">\n\t\t<a\n\t\thref=\"https:\/\/omcabogados.com.pe\/abogados-consultores\/ricardo-checa\/\"\n\t\t\t>\n\tRicardo Checa<\/a><\/h3>\n\n<div class=\"vp-portfolio__item-meta-excerpt\">\n\t<div>\n\t\tabogados8@omcabogados.com\t<\/div>\n<\/div>\n\t\t\t<\/div>\n\t\t<\/div>\n\t<\/figcaption>\n\t\t\t<\/figure>\n\t\t\t\t\t<\/div>\n\t\t\n\t\t<div\t\tclass=\"vp-portfolio__item-wrap vp-portfolio__item-uid-6c50ebe4\" data-vp-filter=\"\" \t\t>\n\t\t\t\t\t\t\t\t\t<figure class=\"vp-portfolio__item\">\n\t\t\t\t\n<div class=\"vp-portfolio__item-img-wrap\">\n\t<div class=\"vp-portfolio__item-img\">\n\t\t\t<a\n\t\thref=\"https:\/\/omcabogados.com.pe\/abogados-consultores\/ingrid-escobar\/\"\n\t\t\t>\n\t\n\t\t<noscript><img loading=\"lazy\" decoding=\"async\" width=\"480\" height=\"480\" data-skip-lazy src=\"https:\/\/omcabogados.com.pe\/wp-content\/uploads\/Ingrid-Escobar-Rodas-1.png\" class=\"wp-image-13819\" alt=\"\" \/><\/noscript><img decoding=\"async\" width=\"480\" height=\"480\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iNDgwIiBoZWlnaHQ9IjQ4MCIgdmlld0JveD0iMCAwIDQ4MCA0ODAiIGZpbGw9Im5vbmUiIHhtbG5zPSJodHRwOi8vd3d3LnczLm9yZy8yMDAwL3N2ZyI+PC9zdmc+\" class=\"wp-image-13819 vp-lazyload\" alt data-src=\"https:\/\/omcabogados.com.pe\/wp-content\/uploads\/Ingrid-Escobar-Rodas-1.png\" data-sizes=\"auto\" loading=\"eager\">\n\t\t<div class=\"vp-portfolio__item-overlay\"><\/div>\n\n\t\t<\/a>\t<\/div>\n<\/div>\n\n\t<figcaption class=\"vp-portfolio__item-caption vp-portfolio__item-caption-text-align-center\">\n\t\t<div class=\"vp-portfolio__item-meta-wrap vp-portfolio__custom-scrollbar\">\n\t\t\t<div class=\"vp-portfolio__item-meta\">\n\t\t\t\t\n<h3 class=\"vp-portfolio__item-meta-title\">\n\t\t<a\n\t\thref=\"https:\/\/omcabogados.com.pe\/abogados-consultores\/ingrid-escobar\/\"\n\t\t\t>\n\tIngrid Escobar Rodas<\/a><\/h3>\n\n<div class=\"vp-portfolio__item-meta-excerpt\">\n\t<div>\n\t\tabogados7@omcabogados.com\t<\/div>\n<\/div>\n\t\t\t<\/div>\n\t\t<\/div>\n\t<\/figcaption>\n\t\t\t<\/figure>\n\t\t\t\t\t<\/div>\n\t\t\n\t\t<div\t\tclass=\"vp-portfolio__item-wrap vp-portfolio__item-uid-048127a5\" data-vp-filter=\"\" \t\t>\n\t\t\t\t\t\t\t\t\t<figure class=\"vp-portfolio__item\">\n\t\t\t\t\n<div class=\"vp-portfolio__item-img-wrap\">\n\t<div class=\"vp-portfolio__item-img\">\n\t\t\t<a\n\t\thref=\"https:\/\/omcabogados.com.pe\/abogados-consultores\/paolo-orlandini\/\"\n\t\t\t>\n\t\n\t\t<noscript><img loading=\"lazy\" decoding=\"async\" width=\"480\" height=\"480\" data-skip-lazy src=\"https:\/\/omcabogados.com.pe\/wp-content\/uploads\/Paolo-Orlandini_sf.png\" class=\"wp-image-9110\" alt=\"\" \/><\/noscript><img decoding=\"async\" width=\"480\" height=\"480\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iNDgwIiBoZWlnaHQ9IjQ4MCIgdmlld0JveD0iMCAwIDQ4MCA0ODAiIGZpbGw9Im5vbmUiIHhtbG5zPSJodHRwOi8vd3d3LnczLm9yZy8yMDAwL3N2ZyI+PC9zdmc+\" class=\"wp-image-9110 vp-lazyload\" alt data-src=\"https:\/\/omcabogados.com.pe\/wp-content\/uploads\/Paolo-Orlandini_sf.png\" data-sizes=\"auto\" loading=\"eager\">\n\t\t<div class=\"vp-portfolio__item-overlay\"><\/div>\n\n\t\t<\/a>\t<\/div>\n<\/div>\n\n\t<figcaption class=\"vp-portfolio__item-caption vp-portfolio__item-caption-text-align-center\">\n\t\t<div class=\"vp-portfolio__item-meta-wrap vp-portfolio__custom-scrollbar\">\n\t\t\t<div class=\"vp-portfolio__item-meta\">\n\t\t\t\t\n<h3 class=\"vp-portfolio__item-meta-title\">\n\t\t<a\n\t\thref=\"https:\/\/omcabogados.com.pe\/abogados-consultores\/paolo-orlandini\/\"\n\t\t\t>\n\tPaolo Orlandini<\/a><\/h3>\n\n<div class=\"vp-portfolio__item-meta-excerpt\">\n\t<div>\n\t\tporlandini@omcpharmamedic.com\t<\/div>\n<\/div>\n\t\t\t<\/div>\n\t\t<\/div>\n\t<\/figcaption>\n\t\t\t<\/figure>\n\t\t\t\t\t<\/div>\n\t\t\n\t\t<div\t\tclass=\"vp-portfolio__item-wrap vp-portfolio__item-uid-c1a6cb23\" data-vp-filter=\"\" \t\t>\n\t\t\t\t\t\t\t\t\t<figure class=\"vp-portfolio__item\">\n\t\t\t\t\n<div class=\"vp-portfolio__item-img-wrap\">\n\t<div class=\"vp-portfolio__item-img\">\n\t\t\t<a\n\t\thref=\"https:\/\/omcabogados.com.pe\/abogados-consultores\/karen-martinez\/\"\n\t\t\t>\n\t\n\t\t<noscript><img loading=\"lazy\" decoding=\"async\" width=\"480\" height=\"480\" data-skip-lazy src=\"https:\/\/omcabogados.com.pe\/wp-content\/uploads\/Karen-Martinez_sf.png\" class=\"wp-image-9111\" alt=\"\" \/><\/noscript><img decoding=\"async\" width=\"480\" height=\"480\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iNDgwIiBoZWlnaHQ9IjQ4MCIgdmlld0JveD0iMCAwIDQ4MCA0ODAiIGZpbGw9Im5vbmUiIHhtbG5zPSJodHRwOi8vd3d3LnczLm9yZy8yMDAwL3N2ZyI+PC9zdmc+\" class=\"wp-image-9111 vp-lazyload\" alt data-src=\"https:\/\/omcabogados.com.pe\/wp-content\/uploads\/Karen-Martinez_sf.png\" data-sizes=\"auto\" loading=\"eager\">\n\t\t<div class=\"vp-portfolio__item-overlay\"><\/div>\n\n\t\t<\/a>\t<\/div>\n<\/div>\n\n\t<figcaption class=\"vp-portfolio__item-caption vp-portfolio__item-caption-text-align-center\">\n\t\t<div class=\"vp-portfolio__item-meta-wrap vp-portfolio__custom-scrollbar\">\n\t\t\t<div class=\"vp-portfolio__item-meta\">\n\t\t\t\t\n<h3 class=\"vp-portfolio__item-meta-title\">\n\t\t<a\n\t\thref=\"https:\/\/omcabogados.com.pe\/abogados-consultores\/karen-martinez\/\"\n\t\t\t>\n\tKaren Martinez<\/a><\/h3>\n\n<div class=\"vp-portfolio__item-meta-excerpt\">\n\t<div>\n\t\tquimica1@omcabogados.com\t<\/div>\n<\/div>\n\t\t\t<\/div>\n\t\t<\/div>\n\t<\/figcaption>\n\t\t\t<\/figure>\n\t\t\t\t\t<\/div>\n\t\t\n\t\t<div\t\tclass=\"vp-portfolio__item-wrap vp-portfolio__item-uid-65cfb329\" data-vp-filter=\"\" \t\t>\n\t\t\t\t\t\t\t\t\t<figure class=\"vp-portfolio__item\">\n\t\t\t\t\n<div class=\"vp-portfolio__item-img-wrap\">\n\t<div class=\"vp-portfolio__item-img\">\n\t\t\t<a\n\t\thref=\"https:\/\/omcabogados.com.pe\/abogados-consultores\/maura-vargas\/\"\n\t\t\t>\n\t\n\t\t<noscript><img loading=\"lazy\" decoding=\"async\" width=\"480\" height=\"480\" data-skip-lazy src=\"https:\/\/omcabogados.com.pe\/wp-content\/uploads\/Maura-Vargas_sf.png\" class=\"wp-image-9112\" alt=\"\" \/><\/noscript><img decoding=\"async\" width=\"480\" height=\"480\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iNDgwIiBoZWlnaHQ9IjQ4MCIgdmlld0JveD0iMCAwIDQ4MCA0ODAiIGZpbGw9Im5vbmUiIHhtbG5zPSJodHRwOi8vd3d3LnczLm9yZy8yMDAwL3N2ZyI+PC9zdmc+\" class=\"wp-image-9112 vp-lazyload\" alt data-src=\"https:\/\/omcabogados.com.pe\/wp-content\/uploads\/Maura-Vargas_sf.png\" data-sizes=\"auto\" loading=\"eager\">\n\t\t<div class=\"vp-portfolio__item-overlay\"><\/div>\n\n\t\t<\/a>\t<\/div>\n<\/div>\n\n\t<figcaption class=\"vp-portfolio__item-caption vp-portfolio__item-caption-text-align-center\">\n\t\t<div class=\"vp-portfolio__item-meta-wrap vp-portfolio__custom-scrollbar\">\n\t\t\t<div class=\"vp-portfolio__item-meta\">\n\t\t\t\t\n<h3 class=\"vp-portfolio__item-meta-title\">\n\t\t<a\n\t\thref=\"https:\/\/omcabogados.com.pe\/abogados-consultores\/maura-vargas\/\"\n\t\t\t>\n\tMaura Vargas<\/a><\/h3>\n\n<div class=\"vp-portfolio__item-meta-excerpt\">\n\t<div>\n\t\tcontabilidad3@omcabogados.com\t<\/div>\n<\/div>\n\t\t\t<\/div>\n\t\t<\/div>\n\t<\/figcaption>\n\t\t\t<\/figure>\n\t\t\t\t\t<\/div>\n\t\t\n\t\t<div\t\tclass=\"vp-portfolio__item-wrap vp-portfolio__item-uid-5568f96f\" data-vp-filter=\"\" \t\t>\n\t\t\t\t\t\t\t\t\t<figure class=\"vp-portfolio__item\">\n\t\t\t\t\n<div class=\"vp-portfolio__item-img-wrap\">\n\t<div class=\"vp-portfolio__item-img\">\n\t\t\t<a\n\t\thref=\"https:\/\/omcabogados.com.pe\/abogados-consultores\/luis-valerio\/\"\n\t\t\t>\n\t\n\t\t<noscript><img loading=\"lazy\" decoding=\"async\" width=\"480\" height=\"480\" data-skip-lazy src=\"https:\/\/omcabogados.com.pe\/wp-content\/uploads\/Luis-Valerio_sf.png\" class=\"wp-image-9113\" alt=\"\" \/><\/noscript><img decoding=\"async\" width=\"480\" height=\"480\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iNDgwIiBoZWlnaHQ9IjQ4MCIgdmlld0JveD0iMCAwIDQ4MCA0ODAiIGZpbGw9Im5vbmUiIHhtbG5zPSJodHRwOi8vd3d3LnczLm9yZy8yMDAwL3N2ZyI+PC9zdmc+\" class=\"wp-image-9113 vp-lazyload\" alt data-src=\"https:\/\/omcabogados.com.pe\/wp-content\/uploads\/Luis-Valerio_sf.png\" data-sizes=\"auto\" loading=\"eager\">\n\t\t<div class=\"vp-portfolio__item-overlay\"><\/div>\n\n\t\t<\/a>\t<\/div>\n<\/div>\n\n\t<figcaption class=\"vp-portfolio__item-caption vp-portfolio__item-caption-text-align-center\">\n\t\t<div class=\"vp-portfolio__item-meta-wrap vp-portfolio__custom-scrollbar\">\n\t\t\t<div class=\"vp-portfolio__item-meta\">\n\t\t\t\t\n<h3 class=\"vp-portfolio__item-meta-title\">\n\t\t<a\n\t\thref=\"https:\/\/omcabogados.com.pe\/abogados-consultores\/luis-valerio\/\"\n\t\t\t>\n\tLuis Valerio<\/a><\/h3>\n\n<div class=\"vp-portfolio__item-meta-excerpt\">\n\t<div>\n\t\tmarketing@omcabogados.com.pe\t<\/div>\n<\/div>\n\t\t\t<\/div>\n\t\t<\/div>\n\t<\/figcaption>\n\t\t\t<\/figure>\n\t\t\t\t\t<\/div>\n\t\t\n\t\t<div\t\tclass=\"vp-portfolio__item-wrap vp-portfolio__item-uid-f66c457c\" data-vp-filter=\"\" \t\t>\n\t\t\t\t\t\t\t\t\t<figure class=\"vp-portfolio__item\">\n\t\t\t\t\n<div class=\"vp-portfolio__item-img-wrap\">\n\t<div class=\"vp-portfolio__item-img\">\n\t\t\t<a\n\t\thref=\"https:\/\/omcabogados.com.pe\/abogados-consultores\/luis-coello\/\"\n\t\t\t>\n\t\n\t\t<noscript><img loading=\"lazy\" decoding=\"async\" width=\"480\" height=\"480\" data-skip-lazy src=\"https:\/\/omcabogados.com.pe\/wp-content\/uploads\/Luis-Coello_sf.png\" class=\"wp-image-9114\" alt=\"\" \/><\/noscript><img decoding=\"async\" width=\"480\" height=\"480\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iNDgwIiBoZWlnaHQ9IjQ4MCIgdmlld0JveD0iMCAwIDQ4MCA0ODAiIGZpbGw9Im5vbmUiIHhtbG5zPSJodHRwOi8vd3d3LnczLm9yZy8yMDAwL3N2ZyI+PC9zdmc+\" class=\"wp-image-9114 vp-lazyload\" alt data-src=\"https:\/\/omcabogados.com.pe\/wp-content\/uploads\/Luis-Coello_sf.png\" data-sizes=\"auto\" loading=\"eager\">\n\t\t<div class=\"vp-portfolio__item-overlay\"><\/div>\n\n\t\t<\/a>\t<\/div>\n<\/div>\n\n\t<figcaption class=\"vp-portfolio__item-caption vp-portfolio__item-caption-text-align-center\">\n\t\t<div class=\"vp-portfolio__item-meta-wrap vp-portfolio__custom-scrollbar\">\n\t\t\t<div class=\"vp-portfolio__item-meta\">\n\t\t\t\t\n<h3 class=\"vp-portfolio__item-meta-title\">\n\t\t<a\n\t\thref=\"https:\/\/omcabogados.com.pe\/abogados-consultores\/luis-coello\/\"\n\t\t\t>\n\tLuis Coello<\/a><\/h3>\n\n<div class=\"vp-portfolio__item-meta-excerpt\">\n\t<div>\n\t\tlcoello@omcabogados.com\t<\/div>\n<\/div>\n\t\t\t<\/div>\n\t\t<\/div>\n\t<\/figcaption>\n\t\t\t<\/figure>\n\t\t\t\t\t<\/div>\n\t\t\n\t\t<div\t\tclass=\"vp-portfolio__item-wrap vp-portfolio__item-uid-033be23b\" data-vp-filter=\"\" \t\t>\n\t\t\t\t\t\t\t\t\t<figure class=\"vp-portfolio__item\">\n\t\t\t\t\n<div class=\"vp-portfolio__item-img-wrap\">\n\t<div class=\"vp-portfolio__item-img\">\n\t\t\t<a\n\t\thref=\"https:\/\/omcabogados.com.pe\/abogados-consultores\/gloria-molina\/\"\n\t\t\t>\n\t\n\t\t<noscript><img loading=\"lazy\" decoding=\"async\" width=\"480\" height=\"480\" data-skip-lazy src=\"https:\/\/omcabogados.com.pe\/wp-content\/uploads\/Gloria_Molina_sf.png\" class=\"wp-image-9115\" alt=\"\" \/><\/noscript><img decoding=\"async\" width=\"480\" height=\"480\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iNDgwIiBoZWlnaHQ9IjQ4MCIgdmlld0JveD0iMCAwIDQ4MCA0ODAiIGZpbGw9Im5vbmUiIHhtbG5zPSJodHRwOi8vd3d3LnczLm9yZy8yMDAwL3N2ZyI+PC9zdmc+\" class=\"wp-image-9115 vp-lazyload\" alt data-src=\"https:\/\/omcabogados.com.pe\/wp-content\/uploads\/Gloria_Molina_sf.png\" data-sizes=\"auto\" loading=\"eager\">\n\t\t<div class=\"vp-portfolio__item-overlay\"><\/div>\n\n\t\t<\/a>\t<\/div>\n<\/div>\n\n\t<figcaption class=\"vp-portfolio__item-caption vp-portfolio__item-caption-text-align-center\">\n\t\t<div class=\"vp-portfolio__item-meta-wrap vp-portfolio__custom-scrollbar\">\n\t\t\t<div class=\"vp-portfolio__item-meta\">\n\t\t\t\t\n<h3 class=\"vp-portfolio__item-meta-title\">\n\t\t<a\n\t\thref=\"https:\/\/omcabogados.com.pe\/abogados-consultores\/gloria-molina\/\"\n\t\t\t>\n\tGloria Molina<\/a><\/h3>\n\n<div class=\"vp-portfolio__item-meta-excerpt\">\n\t<div>\n\t\tsecretaria1@omcabogados.com\t<\/div>\n<\/div>\n\t\t\t<\/div>\n\t\t<\/div>\n\t<\/figcaption>\n\t\t\t<\/figure>\n\t\t\t\t\t<\/div>\n\t\t\n\t\t<div\t\tclass=\"vp-portfolio__item-wrap vp-portfolio__item-uid-8e5d1b6e\" data-vp-filter=\"\" \t\t>\n\t\t\t\t\t\t\t\t\t<figure class=\"vp-portfolio__item\">\n\t\t\t\t\n<div class=\"vp-portfolio__item-img-wrap\">\n\t<div class=\"vp-portfolio__item-img\">\n\t\t\t<a\n\t\thref=\"https:\/\/omcabogados.com.pe\/abogados-consultores\/german-bobadilla\/\"\n\t\t\t>\n\t\n\t\t<noscript><img loading=\"lazy\" decoding=\"async\" width=\"480\" height=\"480\" data-skip-lazy src=\"https:\/\/omcabogados.com.pe\/wp-content\/uploads\/german-bobadilla-sf.png\" class=\"wp-image-9622\" alt=\"\" \/><\/noscript><img decoding=\"async\" width=\"480\" height=\"480\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iNDgwIiBoZWlnaHQ9IjQ4MCIgdmlld0JveD0iMCAwIDQ4MCA0ODAiIGZpbGw9Im5vbmUiIHhtbG5zPSJodHRwOi8vd3d3LnczLm9yZy8yMDAwL3N2ZyI+PC9zdmc+\" class=\"wp-image-9622 vp-lazyload\" alt data-src=\"https:\/\/omcabogados.com.pe\/wp-content\/uploads\/german-bobadilla-sf.png\" data-sizes=\"auto\" loading=\"eager\">\n\t\t<div class=\"vp-portfolio__item-overlay\"><\/div>\n\n\t\t<\/a>\t<\/div>\n<\/div>\n\n\t<figcaption class=\"vp-portfolio__item-caption vp-portfolio__item-caption-text-align-center\">\n\t\t<div class=\"vp-portfolio__item-meta-wrap vp-portfolio__custom-scrollbar\">\n\t\t\t<div class=\"vp-portfolio__item-meta\">\n\t\t\t\t\n<h3 class=\"vp-portfolio__item-meta-title\">\n\t\t<a\n\t\thref=\"https:\/\/omcabogados.com.pe\/abogados-consultores\/german-bobadilla\/\"\n\t\t\t>\n\tGerman Bobadilla<\/a><\/h3>\n\n<div class=\"vp-portfolio__item-meta-excerpt\">\n\t<div>\n\t\tgbobadilla@omcabogados.com\t<\/div>\n<\/div>\n\t\t\t<\/div>\n\t\t<\/div>\n\t<\/figcaption>\n\t\t\t<\/figure>\n\t\t\t\t\t<\/div>\n\t\t\n\t\t<div\t\tclass=\"vp-portfolio__item-wrap vp-portfolio__item-uid-b902ec69\" data-vp-filter=\"\" \t\t>\n\t\t\t\t\t\t\t\t\t<figure class=\"vp-portfolio__item\">\n\t\t\t\t\n<div class=\"vp-portfolio__item-img-wrap\">\n\t<div class=\"vp-portfolio__item-img\">\n\t\t\t<a\n\t\thref=\"https:\/\/omcabogados.com.pe\/abogados-consultores\/max-del-mar\/\"\n\t\t\t>\n\t\n\t\t<noscript><img loading=\"lazy\" decoding=\"async\" width=\"480\" height=\"480\" data-skip-lazy src=\"https:\/\/omcabogados.com.pe\/wp-content\/uploads\/max-del-mar.png\" class=\"wp-image-16016\" alt=\"\" \/><\/noscript><img decoding=\"async\" width=\"480\" height=\"480\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iNDgwIiBoZWlnaHQ9IjQ4MCIgdmlld0JveD0iMCAwIDQ4MCA0ODAiIGZpbGw9Im5vbmUiIHhtbG5zPSJodHRwOi8vd3d3LnczLm9yZy8yMDAwL3N2ZyI+PC9zdmc+\" class=\"wp-image-16016 vp-lazyload\" alt data-src=\"https:\/\/omcabogados.com.pe\/wp-content\/uploads\/max-del-mar.png\" data-sizes=\"auto\" loading=\"eager\">\n\t\t<div class=\"vp-portfolio__item-overlay\"><\/div>\n\n\t\t<\/a>\t<\/div>\n<\/div>\n\n\t<figcaption class=\"vp-portfolio__item-caption vp-portfolio__item-caption-text-align-center\">\n\t\t<div class=\"vp-portfolio__item-meta-wrap vp-portfolio__custom-scrollbar\">\n\t\t\t<div class=\"vp-portfolio__item-meta\">\n\t\t\t\t\n<h3 class=\"vp-portfolio__item-meta-title\">\n\t\t<a\n\t\thref=\"https:\/\/omcabogados.com.pe\/abogados-consultores\/max-del-mar\/\"\n\t\t\t>\n\tMax Del Mar<\/a><\/h3>\n\n<div class=\"vp-portfolio__item-meta-excerpt\">\n\t<div>\n\t\tsistemas1@omcabogados.com\t<\/div>\n<\/div>\n\t\t\t<\/div>\n\t\t<\/div>\n\t<\/figcaption>\n\t\t\t<\/figure>\n\t\t\t\t\t<\/div>\n\t\t\n<\/div>\n\t\t<\/div>\n\t\t\n<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>Abogados &#038; Consultores E-mail: fmevius@omcabogados.com Facebook Instagram Linkedin Twitter Federico Mevius Pigati \u00c1REAS DE ESPECIALIZACI\u00d3N Derecho corporativo.Derecho laboral.Propiedad intelectual.Licitaciones y ofertas p\u00fablicas. IDIOMAS Espa\u00f1olIngl\u00e9s ABOGADOS &#038; CONSULTORES<\/p>\n","protected":false},"author":1,"featured_media":0,"parent":9088,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_vp_format_video_url":"","_vp_image_focal_point":[],"_vp_custom_popup_image":0,"_vp_format_audio_url":"","_vp_custom_thumbnail":0,"_vp_custom_thumbnail_focal_point":[],"_vp_hover_thumbnail":0,"_vp_hover_thumbnail_focal_point":[],"footnotes":""},"class_list":["post-8910","page","type-page","status-publish","hentry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.2 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Federico Mevius Pigati - OMC Abogados &amp; Consultores<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/omcabogados.com.pe\/es\/abogados-consultores\/federico-mevius-pigati\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Federico Mevius Pigati - OMC Abogados &amp; Consultores\" \/>\n<meta property=\"og:description\" content=\"Abogados &#038; Consultores E-mail: fmevius@omcabogados.com Facebook Instagram Linkedin Twitter Federico Mevius Pigati \u00c1REAS DE ESPECIALIZACI\u00d3N Derecho corporativo.Derecho laboral.Propiedad intelectual.Licitaciones y ofertas p\u00fablicas. IDIOMAS Espa\u00f1olIngl\u00e9s ABOGADOS &#038; CONSULTORES\" \/>\n<meta property=\"og:url\" content=\"https:\/\/omcabogados.com.pe\/es\/abogados-consultores\/federico-mevius-pigati\/\" \/>\n<meta property=\"og:site_name\" content=\"OMC Abogados &amp; Consultores\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/omcabogados.consultores\/\" \/>\n<meta property=\"article:modified_time\" content=\"2024-01-30T21:35:07+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/omcabogados.com.pe\/wp-content\/uploads\/elementor\/thumbs\/Federico-Mevius_sf-qgbc6qnhik3ob4u6zbth78r3kk67is0kf10uw18qd0.png\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@omcabogadosperu\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/omcabogados.com.pe\\\/abogados-consultores\\\/federico-mevius-pigati\\\/\",\"url\":\"https:\\\/\\\/omcabogados.com.pe\\\/abogados-consultores\\\/federico-mevius-pigati\\\/\",\"name\":\"Federico Mevius Pigati - OMC Abogados &amp; Consultores\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/omcabogados.com.pe\\\/es\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/omcabogados.com.pe\\\/abogados-consultores\\\/federico-mevius-pigati\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/omcabogados.com.pe\\\/abogados-consultores\\\/federico-mevius-pigati\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/omcabogados.com.pe\\\/wp-content\\\/uploads\\\/elementor\\\/thumbs\\\/Federico-Mevius_sf-qgbc6qnhik3ob4u6zbth78r3kk67is0kf10uw18qd0.png\",\"datePublished\":\"2023-11-29T20:02:05+00:00\",\"dateModified\":\"2024-01-30T21:35:07+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/omcabogados.com.pe\\\/abogados-consultores\\\/federico-mevius-pigati\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/omcabogados.com.pe\\\/abogados-consultores\\\/federico-mevius-pigati\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/omcabogados.com.pe\\\/abogados-consultores\\\/federico-mevius-pigati\\\/#primaryimage\",\"url\":\"https:\\\/\\\/omcabogados.com.pe\\\/wp-content\\\/uploads\\\/elementor\\\/thumbs\\\/Federico-Mevius_sf-qgbc6qnhik3ob4u6zbth78r3kk67is0kf10uw18qd0.png\",\"contentUrl\":\"https:\\\/\\\/omcabogados.com.pe\\\/wp-content\\\/uploads\\\/elementor\\\/thumbs\\\/Federico-Mevius_sf-qgbc6qnhik3ob4u6zbth78r3kk67is0kf10uw18qd0.png\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/omcabogados.com.pe\\\/abogados-consultores\\\/federico-mevius-pigati\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/omcabogados.com.pe\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Abogados &#038; Consultores\",\"item\":\"https:\\\/\\\/omcabogados.com.pe\\\/abogados-consultores\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Federico Mevius Pigati\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/omcabogados.com.pe\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/omcabogados.com.pe\\\/es\\\/\",\"name\":\"OMC Abogados & Consultores\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/omcabogados.com.pe\\\/es\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/omcabogados.com.pe\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/omcabogados.com.pe\\\/es\\\/#organization\",\"name\":\"OMC Abogados & Consultores\",\"url\":\"https:\\\/\\\/omcabogados.com.pe\\\/es\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/omcabogados.com.pe\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/omcabogados.com.pe\\\/wp-content\\\/uploads\\\/logo-omc-abogados.png\",\"contentUrl\":\"https:\\\/\\\/omcabogados.com.pe\\\/wp-content\\\/uploads\\\/logo-omc-abogados.png\",\"width\":210,\"height\":159,\"caption\":\"OMC Abogados & Consultores\"},\"image\":{\"@id\":\"https:\\\/\\\/omcabogados.com.pe\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/omcabogados.consultores\\\/\",\"https:\\\/\\\/x.com\\\/omcabogadosperu\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/omc-abogados-consultores\\\/?viewAsMember=true\",\"https:\\\/\\\/www.instagram.com\\\/omcabogadosyconsultores\\\/\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Federico Mevius Pigati - OMC Abogados &amp; Consultores","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/omcabogados.com.pe\/es\/abogados-consultores\/federico-mevius-pigati\/","og_locale":"es_ES","og_type":"article","og_title":"Federico Mevius Pigati - OMC Abogados &amp; Consultores","og_description":"Abogados &#038; Consultores E-mail: fmevius@omcabogados.com Facebook Instagram Linkedin Twitter Federico Mevius Pigati \u00c1REAS DE ESPECIALIZACI\u00d3N Derecho corporativo.Derecho laboral.Propiedad intelectual.Licitaciones y ofertas p\u00fablicas. IDIOMAS Espa\u00f1olIngl\u00e9s ABOGADOS &#038; CONSULTORES","og_url":"https:\/\/omcabogados.com.pe\/es\/abogados-consultores\/federico-mevius-pigati\/","og_site_name":"OMC Abogados &amp; Consultores","article_publisher":"https:\/\/www.facebook.com\/omcabogados.consultores\/","article_modified_time":"2024-01-30T21:35:07+00:00","og_image":[{"url":"https:\/\/omcabogados.com.pe\/wp-content\/uploads\/elementor\/thumbs\/Federico-Mevius_sf-qgbc6qnhik3ob4u6zbth78r3kk67is0kf10uw18qd0.png","type":"","width":"","height":""}],"twitter_card":"summary_large_image","twitter_site":"@omcabogadosperu","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/omcabogados.com.pe\/abogados-consultores\/federico-mevius-pigati\/","url":"https:\/\/omcabogados.com.pe\/abogados-consultores\/federico-mevius-pigati\/","name":"Federico Mevius Pigati - OMC Abogados &amp; Consultores","isPartOf":{"@id":"https:\/\/omcabogados.com.pe\/es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/omcabogados.com.pe\/abogados-consultores\/federico-mevius-pigati\/#primaryimage"},"image":{"@id":"https:\/\/omcabogados.com.pe\/abogados-consultores\/federico-mevius-pigati\/#primaryimage"},"thumbnailUrl":"https:\/\/omcabogados.com.pe\/wp-content\/uploads\/elementor\/thumbs\/Federico-Mevius_sf-qgbc6qnhik3ob4u6zbth78r3kk67is0kf10uw18qd0.png","datePublished":"2023-11-29T20:02:05+00:00","dateModified":"2024-01-30T21:35:07+00:00","breadcrumb":{"@id":"https:\/\/omcabogados.com.pe\/abogados-consultores\/federico-mevius-pigati\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/omcabogados.com.pe\/abogados-consultores\/federico-mevius-pigati\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/omcabogados.com.pe\/abogados-consultores\/federico-mevius-pigati\/#primaryimage","url":"https:\/\/omcabogados.com.pe\/wp-content\/uploads\/elementor\/thumbs\/Federico-Mevius_sf-qgbc6qnhik3ob4u6zbth78r3kk67is0kf10uw18qd0.png","contentUrl":"https:\/\/omcabogados.com.pe\/wp-content\/uploads\/elementor\/thumbs\/Federico-Mevius_sf-qgbc6qnhik3ob4u6zbth78r3kk67is0kf10uw18qd0.png"},{"@type":"BreadcrumbList","@id":"https:\/\/omcabogados.com.pe\/abogados-consultores\/federico-mevius-pigati\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/omcabogados.com.pe\/"},{"@type":"ListItem","position":2,"name":"Abogados &#038; Consultores","item":"https:\/\/omcabogados.com.pe\/abogados-consultores\/"},{"@type":"ListItem","position":3,"name":"Federico Mevius Pigati"}]},{"@type":"WebSite","@id":"https:\/\/omcabogados.com.pe\/es\/#website","url":"https:\/\/omcabogados.com.pe\/es\/","name":"OMC Abogados & Consultores","description":"","publisher":{"@id":"https:\/\/omcabogados.com.pe\/es\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/omcabogados.com.pe\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/omcabogados.com.pe\/es\/#organization","name":"OMC Abogados & Consultores","url":"https:\/\/omcabogados.com.pe\/es\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/omcabogados.com.pe\/es\/#\/schema\/logo\/image\/","url":"https:\/\/omcabogados.com.pe\/wp-content\/uploads\/logo-omc-abogados.png","contentUrl":"https:\/\/omcabogados.com.pe\/wp-content\/uploads\/logo-omc-abogados.png","width":210,"height":159,"caption":"OMC Abogados & Consultores"},"image":{"@id":"https:\/\/omcabogados.com.pe\/es\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/omcabogados.consultores\/","https:\/\/x.com\/omcabogadosperu","https:\/\/www.linkedin.com\/company\/omc-abogados-consultores\/?viewAsMember=true","https:\/\/www.instagram.com\/omcabogadosyconsultores\/"]}]}},"rttpg_featured_image_url":null,"rttpg_author":{"display_name":"WebMasterOMC","author_link":"https:\/\/omcabogados.com.pe\/es\/author\/webmasteromc\/"},"rttpg_comment":0,"rttpg_category":null,"rttpg_excerpt":"Abogados &#038; Consultores E-mail: fmevius@omcabogados.com Facebook Instagram Linkedin Twitter Federico Mevius Pigati \u00c1REAS DE ESPECIALIZACI\u00d3N Derecho corporativo.Derecho laboral.Propiedad intelectual.Licitaciones y ofertas p\u00fablicas. IDIOMAS Espa\u00f1olIngl\u00e9s ABOGADOS &#038; CONSULTORES","_links":{"self":[{"href":"https:\/\/omcabogados.com.pe\/es\/wp-json\/wp\/v2\/pages\/8910","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/omcabogados.com.pe\/es\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/omcabogados.com.pe\/es\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/omcabogados.com.pe\/es\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/omcabogados.com.pe\/es\/wp-json\/wp\/v2\/comments?post=8910"}],"version-history":[{"count":25,"href":"https:\/\/omcabogados.com.pe\/es\/wp-json\/wp\/v2\/pages\/8910\/revisions"}],"predecessor-version":[{"id":10084,"href":"https:\/\/omcabogados.com.pe\/es\/wp-json\/wp\/v2\/pages\/8910\/revisions\/10084"}],"up":[{"embeddable":true,"href":"https:\/\/omcabogados.com.pe\/es\/wp-json\/wp\/v2\/pages\/9088"}],"wp:attachment":[{"href":"https:\/\/omcabogados.com.pe\/es\/wp-json\/wp\/v2\/media?parent=8910"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}