{"id":16915,"date":"2026-06-19T17:43:04","date_gmt":"2026-06-19T22:43:04","guid":{"rendered":"https:\/\/omcabogados.com.pe\/?p=16915"},"modified":"2026-06-24T15:58:12","modified_gmt":"2026-06-24T20:58:12","slug":"omc-abogados-y-consultores-actualidad-de-la-propiedad-intelectual-en-latinoamerica","status":"publish","type":"post","link":"https:\/\/omcabogados.com.pe\/en\/omc-abogados-y-consultores-intellectual-property-updates-in-latin-america\/","title":{"rendered":"OMC Abogados &amp; Consultores: Intellectual Property Updates in Latin America"},"content":{"rendered":"<p>As specialists in Intellectual Property in Latin America, OMC Abogados &amp; Consultores informs that during the first months of the year changes have been implemented focused on streamlining procedures and reducing the times to process patents and register trademarks in the region.<\/p>\n<p><strong>Intellectual Property Update in Latin America: Mexico and Argentina announced changes in their processes for patent registration<\/strong><\/p>\n<p>The modifications announced by the respective authorities of the sector aim to accelerate the substantive examination for patent applications, which in the case of <a href=\"https:\/\/www.gob.mx\/\"><strong>M\u00e9xico<\/strong><\/a> incluye tambi\u00e9n a los Modelos de Utilidad.<\/p>\n<p>El <a href=\"https:\/\/www.gob.mx\/impi\"><strong>Mexican Institute of Industrial Property (IMPI) <\/strong><\/a>has ordered the reduction of official actions from four to two for the substantive examination of a patent or utility model application. Likewise, virtual meetings between the applicant and the examiner remain authorized during any stage of said examination, allowing the <strong><a href=\"https:\/\/www.gob.mx\/impi\">IMPI<\/a><\/strong> representative to propose a technical meeting after the first official action.<\/p>\n<p>For its part, the <a href=\"https:\/\/portaltramites.inpi.gob.ar\/Home\/index\"><strong>Instituto Nacional de la Propiedad Industrial (INPI)<\/strong><\/a> of <a href=\"https:\/\/www.argentina.gob.ar\/\"><strong>Argentina<\/strong><\/a>, through <a href=\"https:\/\/www.boletinoficial.gob.ar\/detalleAviso\/primera\/341876\/20260513\"><strong>Resolution INPI N\u00b0 142\/2026<\/strong><\/a>, has established the validity of the following requirements to expedite the process:<\/p>\n<p>- That an equivalent patent already granted abroad exists.<br \/>\n- That the patentability criteria applied by the office of origin match those provided by Argentine legislation.<br \/>\n- That the scope of the claims of the Argentine application is equal to or more limited than that of those granted abroad.<br \/>\n- That the national claims are presented duly translated.<br \/>\n- That no national antecedents exist that affect the patentability of the application.<br \/>\n- That the request is filed before the application is granted or denied in Argentina.<br \/>\n- To pay the fee corresponding to the service<\/p>\n<p><strong>Update: Modifications for trademark registration in Argentina<\/strong><\/p>\n<p>Through <a href=\"http:\/\/www.boletinoficial.gob.ar\/detalleAviso\/primera\/335945\/20251211\"><strong>Resolution INPI P-583\/25<\/strong><\/a>the <a href=\"https:\/\/portaltramites.inpi.gob.ar\/Home\/index\"><strong>National Institute of Industrial Property of Argentina (INPI)<\/strong><\/a> announced the modifications for trademark registration in <a href=\"https:\/\/www.argentina.gob.ar\/\"><strong>Argentina<\/strong><\/a>announced the modifications for trademark registration in Argentina, where substantive and formal examinations will be carried out jointly at the beginning of the registration process. Under this modality, only absolute prohibitions related to public order, lack of distinctiveness, the prior existence of identical trademarks, or the presence of signs contrary to morality and good customs will be reviewed.<\/p>\n<p>If you find this information useful, we invite you to save and share it. OMC Abogados &amp; Consultores is at your full disposal should you require specialized legal counsel on this matter: https:\/\/omcabogados.com.pe\/es\/consultas-legales-peru-latinoamerica\/<\/p>\n<p>&nbsp;<\/p>","protected":false},"excerpt":{"rendered":"<p>Como especialistas en Propiedad Intelectual en Latinoam\u00e9rica, OMC Abogados &amp; Consultores informa que durante los primeros meses del a\u00f1o se han implementado cambios enfocados en agilizar los procedimientos y reducir los tiempos para tramitar patentes y registrar marcas en la regi\u00f3n. Actualidad de la Propiedad Intelectual en Latinoam\u00e9rica: M\u00e9xico y Argentina anunciaron cambios en sus [&hellip;]<\/p>","protected":false},"author":2,"featured_media":16914,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_vp_format_video_url":"","_vp_image_focal_point":[],"_vp_custom_popup_image":0,"_vp_format_audio_url":"","_vp_custom_thumbnail":0,"_vp_custom_thumbnail_focal_point":[],"_vp_hover_thumbnail":0,"_vp_hover_thumbnail_focal_point":[],"footnotes":""},"categories":[45],"tags":[173,186,156,187,84,79,82,77,89],"class_list":["post-16915","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-notas-de-prensa","tag-argentina","tag-impi","tag-inpi","tag-mexico","tag-modelos-de-utilidad","tag-omc-abogados-consultores","tag-patentes","tag-propiedad-intelectual","tag-registro-de-marcas"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.9 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>- OMC Abogados &amp; Consultores<\/title>\n<meta name=\"description\" content=\"Conozca los cambios regulatorios de 2026 en M\u00e9xico y Argentina para agilizar el registro de patentes y marcas en Latinoam\u00e9rica.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/omcabogados.com.pe\/en\/omc-abogados-y-consultores-intellectual-property-updates-in-latin-america\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"- OMC Abogados &amp; Consultores\" \/>\n<meta property=\"og:description\" content=\"Conozca los cambios regulatorios de 2026 en M\u00e9xico y Argentina para agilizar el registro de patentes y marcas en Latinoam\u00e9rica.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/omcabogados.com.pe\/en\/omc-abogados-y-consultores-intellectual-property-updates-in-latin-america\/\" \/>\n<meta property=\"og:site_name\" content=\"OMC Abogados &amp; Consultores\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/omcabogados.consultores\/\" \/>\n<meta property=\"article:published_time\" content=\"2026-06-19T22:43:04+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2026-06-24T20:58:12+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/omcabogados.com.pe\/wp-content\/uploads\/omc-abogados-y-consultores-actualidad-de-la-propiedad-intelectual-en-latinoamerica.webp\" \/>\n\t<meta property=\"og:image:width\" content=\"660\" \/>\n\t<meta property=\"og:image:height\" content=\"440\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/webp\" \/>\n<meta name=\"author\" content=\"Luis Valerio\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@omcabogadosperu\" \/>\n<meta name=\"twitter:site\" content=\"@omcabogadosperu\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"Luis Valerio\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/omcabogados.com.pe\\\/omc-abogados-y-consultores-actualidad-de-la-propiedad-intelectual-en-latinoamerica\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/omcabogados.com.pe\\\/omc-abogados-y-consultores-actualidad-de-la-propiedad-intelectual-en-latinoamerica\\\/\"},\"author\":{\"name\":\"Luis Valerio\",\"@id\":\"https:\\\/\\\/omcabogados.com.pe\\\/es\\\/#\\\/schema\\\/person\\\/a09a3c55e7d9fbc43450f286a70f9211\"},\"headline\":\"OMC Abogados &#038; Consultores: La actualidad de la propiedad intelectual en Latinoam\u00e9rica\",\"datePublished\":\"2026-06-19T22:43:04+00:00\",\"dateModified\":\"2026-06-24T20:58:12+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/omcabogados.com.pe\\\/omc-abogados-y-consultores-actualidad-de-la-propiedad-intelectual-en-latinoamerica\\\/\"},\"wordCount\":475,\"publisher\":{\"@id\":\"https:\\\/\\\/omcabogados.com.pe\\\/es\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/omcabogados.com.pe\\\/omc-abogados-y-consultores-actualidad-de-la-propiedad-intelectual-en-latinoamerica\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/omcabogados.com.pe\\\/wp-content\\\/uploads\\\/omc-abogados-y-consultores-actualidad-de-la-propiedad-intelectual-en-latinoamerica.webp\",\"keywords\":[\"Argentina\",\"IMPI\",\"INPI\",\"M\u00e9xico\",\"Modelos-de-utilidad\",\"OMC Abogados &amp; Consultores\",\"Patentes\",\"Propiedad Intelectual\",\"Registro de marcas\"],\"articleSection\":[\"Notas de Prensa\"],\"inLanguage\":\"en-US\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/omcabogados.com.pe\\\/omc-abogados-y-consultores-actualidad-de-la-propiedad-intelectual-en-latinoamerica\\\/\",\"url\":\"https:\\\/\\\/omcabogados.com.pe\\\/omc-abogados-y-consultores-actualidad-de-la-propiedad-intelectual-en-latinoamerica\\\/\",\"name\":\"- OMC Abogados &amp; Consultores\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/omcabogados.com.pe\\\/es\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/omcabogados.com.pe\\\/omc-abogados-y-consultores-actualidad-de-la-propiedad-intelectual-en-latinoamerica\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/omcabogados.com.pe\\\/omc-abogados-y-consultores-actualidad-de-la-propiedad-intelectual-en-latinoamerica\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/omcabogados.com.pe\\\/wp-content\\\/uploads\\\/omc-abogados-y-consultores-actualidad-de-la-propiedad-intelectual-en-latinoamerica.webp\",\"datePublished\":\"2026-06-19T22:43:04+00:00\",\"dateModified\":\"2026-06-24T20:58:12+00:00\",\"description\":\"Conozca los cambios regulatorios de 2026 en M\u00e9xico y Argentina para agilizar el registro de patentes y marcas en Latinoam\u00e9rica.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/omcabogados.com.pe\\\/omc-abogados-y-consultores-actualidad-de-la-propiedad-intelectual-en-latinoamerica\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/omcabogados.com.pe\\\/omc-abogados-y-consultores-actualidad-de-la-propiedad-intelectual-en-latinoamerica\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/omcabogados.com.pe\\\/omc-abogados-y-consultores-actualidad-de-la-propiedad-intelectual-en-latinoamerica\\\/#primaryimage\",\"url\":\"https:\\\/\\\/omcabogados.com.pe\\\/wp-content\\\/uploads\\\/omc-abogados-y-consultores-actualidad-de-la-propiedad-intelectual-en-latinoamerica.webp\",\"contentUrl\":\"https:\\\/\\\/omcabogados.com.pe\\\/wp-content\\\/uploads\\\/omc-abogados-y-consultores-actualidad-de-la-propiedad-intelectual-en-latinoamerica.webp\",\"width\":660,\"height\":440},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/omcabogados.com.pe\\\/omc-abogados-y-consultores-actualidad-de-la-propiedad-intelectual-en-latinoamerica\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/omcabogados.com.pe\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"OMC Abogados &#038; Consultores: La actualidad de la propiedad intelectual en Latinoam\u00e9rica\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/omcabogados.com.pe\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/omcabogados.com.pe\\\/es\\\/\",\"name\":\"OMC Abogados & Consultores\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/omcabogados.com.pe\\\/es\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/omcabogados.com.pe\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/omcabogados.com.pe\\\/es\\\/#organization\",\"name\":\"OMC Abogados & Consultores\",\"url\":\"https:\\\/\\\/omcabogados.com.pe\\\/es\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/omcabogados.com.pe\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/omcabogados.com.pe\\\/wp-content\\\/uploads\\\/logo-omc-abogados.png\",\"contentUrl\":\"https:\\\/\\\/omcabogados.com.pe\\\/wp-content\\\/uploads\\\/logo-omc-abogados.png\",\"width\":210,\"height\":159,\"caption\":\"OMC Abogados & Consultores\"},\"image\":{\"@id\":\"https:\\\/\\\/omcabogados.com.pe\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/omcabogados.consultores\\\/\",\"https:\\\/\\\/x.com\\\/omcabogadosperu\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/omc-abogados-consultores\\\/?viewAsMember=true\",\"https:\\\/\\\/www.instagram.com\\\/omcabogadosyconsultores\\\/\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/omcabogados.com.pe\\\/es\\\/#\\\/schema\\\/person\\\/a09a3c55e7d9fbc43450f286a70f9211\",\"name\":\"Luis Valerio\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/cb548e4205775273d33308ca72a531966ded49102d271cbad24375f4fb220e19?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/cb548e4205775273d33308ca72a531966ded49102d271cbad24375f4fb220e19?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/cb548e4205775273d33308ca72a531966ded49102d271cbad24375f4fb220e19?s=96&d=mm&r=g\",\"caption\":\"Luis Valerio\"},\"url\":\"https:\\\/\\\/omcabogados.com.pe\\\/en\\\/author\\\/luisvalerio\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"- OMC Abogados &amp; Consultores","description":"Conozca los cambios regulatorios de 2026 en M\u00e9xico y Argentina para agilizar el registro de patentes y marcas en Latinoam\u00e9rica.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/omcabogados.com.pe\/en\/omc-abogados-y-consultores-intellectual-property-updates-in-latin-america\/","og_locale":"en_US","og_type":"article","og_title":"- OMC Abogados &amp; Consultores","og_description":"Conozca los cambios regulatorios de 2026 en M\u00e9xico y Argentina para agilizar el registro de patentes y marcas en Latinoam\u00e9rica.","og_url":"https:\/\/omcabogados.com.pe\/en\/omc-abogados-y-consultores-intellectual-property-updates-in-latin-america\/","og_site_name":"OMC Abogados &amp; Consultores","article_publisher":"https:\/\/www.facebook.com\/omcabogados.consultores\/","article_published_time":"2026-06-19T22:43:04+00:00","article_modified_time":"2026-06-24T20:58:12+00:00","og_image":[{"width":660,"height":440,"url":"https:\/\/omcabogados.com.pe\/wp-content\/uploads\/omc-abogados-y-consultores-actualidad-de-la-propiedad-intelectual-en-latinoamerica.webp","type":"image\/webp"}],"author":"Luis Valerio","twitter_card":"summary_large_image","twitter_creator":"@omcabogadosperu","twitter_site":"@omcabogadosperu","twitter_misc":{"Written by":"Luis Valerio","Est. reading time":"3 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/omcabogados.com.pe\/omc-abogados-y-consultores-actualidad-de-la-propiedad-intelectual-en-latinoamerica\/#article","isPartOf":{"@id":"https:\/\/omcabogados.com.pe\/omc-abogados-y-consultores-actualidad-de-la-propiedad-intelectual-en-latinoamerica\/"},"author":{"name":"Luis Valerio","@id":"https:\/\/omcabogados.com.pe\/es\/#\/schema\/person\/a09a3c55e7d9fbc43450f286a70f9211"},"headline":"OMC Abogados &#038; Consultores: La actualidad de la propiedad intelectual en Latinoam\u00e9rica","datePublished":"2026-06-19T22:43:04+00:00","dateModified":"2026-06-24T20:58:12+00:00","mainEntityOfPage":{"@id":"https:\/\/omcabogados.com.pe\/omc-abogados-y-consultores-actualidad-de-la-propiedad-intelectual-en-latinoamerica\/"},"wordCount":475,"publisher":{"@id":"https:\/\/omcabogados.com.pe\/es\/#organization"},"image":{"@id":"https:\/\/omcabogados.com.pe\/omc-abogados-y-consultores-actualidad-de-la-propiedad-intelectual-en-latinoamerica\/#primaryimage"},"thumbnailUrl":"https:\/\/omcabogados.com.pe\/wp-content\/uploads\/omc-abogados-y-consultores-actualidad-de-la-propiedad-intelectual-en-latinoamerica.webp","keywords":["Argentina","IMPI","INPI","M\u00e9xico","Modelos-de-utilidad","OMC Abogados &amp; Consultores","Patentes","Propiedad Intelectual","Registro de marcas"],"articleSection":["Notas de Prensa"],"inLanguage":"en-US"},{"@type":"WebPage","@id":"https:\/\/omcabogados.com.pe\/omc-abogados-y-consultores-actualidad-de-la-propiedad-intelectual-en-latinoamerica\/","url":"https:\/\/omcabogados.com.pe\/omc-abogados-y-consultores-actualidad-de-la-propiedad-intelectual-en-latinoamerica\/","name":"- OMC Abogados &amp; Consultores","isPartOf":{"@id":"https:\/\/omcabogados.com.pe\/es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/omcabogados.com.pe\/omc-abogados-y-consultores-actualidad-de-la-propiedad-intelectual-en-latinoamerica\/#primaryimage"},"image":{"@id":"https:\/\/omcabogados.com.pe\/omc-abogados-y-consultores-actualidad-de-la-propiedad-intelectual-en-latinoamerica\/#primaryimage"},"thumbnailUrl":"https:\/\/omcabogados.com.pe\/wp-content\/uploads\/omc-abogados-y-consultores-actualidad-de-la-propiedad-intelectual-en-latinoamerica.webp","datePublished":"2026-06-19T22:43:04+00:00","dateModified":"2026-06-24T20:58:12+00:00","description":"Conozca los cambios regulatorios de 2026 en M\u00e9xico y Argentina para agilizar el registro de patentes y marcas en Latinoam\u00e9rica.","breadcrumb":{"@id":"https:\/\/omcabogados.com.pe\/omc-abogados-y-consultores-actualidad-de-la-propiedad-intelectual-en-latinoamerica\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/omcabogados.com.pe\/omc-abogados-y-consultores-actualidad-de-la-propiedad-intelectual-en-latinoamerica\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/omcabogados.com.pe\/omc-abogados-y-consultores-actualidad-de-la-propiedad-intelectual-en-latinoamerica\/#primaryimage","url":"https:\/\/omcabogados.com.pe\/wp-content\/uploads\/omc-abogados-y-consultores-actualidad-de-la-propiedad-intelectual-en-latinoamerica.webp","contentUrl":"https:\/\/omcabogados.com.pe\/wp-content\/uploads\/omc-abogados-y-consultores-actualidad-de-la-propiedad-intelectual-en-latinoamerica.webp","width":660,"height":440},{"@type":"BreadcrumbList","@id":"https:\/\/omcabogados.com.pe\/omc-abogados-y-consultores-actualidad-de-la-propiedad-intelectual-en-latinoamerica\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/omcabogados.com.pe\/"},{"@type":"ListItem","position":2,"name":"OMC Abogados &#038; Consultores: La actualidad de la propiedad intelectual en Latinoam\u00e9rica"}]},{"@type":"WebSite","@id":"https:\/\/omcabogados.com.pe\/es\/#website","url":"https:\/\/omcabogados.com.pe\/es\/","name":"OMC Abogados & Consultores","description":"","publisher":{"@id":"https:\/\/omcabogados.com.pe\/es\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/omcabogados.com.pe\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/omcabogados.com.pe\/es\/#organization","name":"OMC Abogados & Consultores","url":"https:\/\/omcabogados.com.pe\/es\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/omcabogados.com.pe\/es\/#\/schema\/logo\/image\/","url":"https:\/\/omcabogados.com.pe\/wp-content\/uploads\/logo-omc-abogados.png","contentUrl":"https:\/\/omcabogados.com.pe\/wp-content\/uploads\/logo-omc-abogados.png","width":210,"height":159,"caption":"OMC Abogados & Consultores"},"image":{"@id":"https:\/\/omcabogados.com.pe\/es\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/omcabogados.consultores\/","https:\/\/x.com\/omcabogadosperu","https:\/\/www.linkedin.com\/company\/omc-abogados-consultores\/?viewAsMember=true","https:\/\/www.instagram.com\/omcabogadosyconsultores\/"]},{"@type":"Person","@id":"https:\/\/omcabogados.com.pe\/es\/#\/schema\/person\/a09a3c55e7d9fbc43450f286a70f9211","name":"Luis Valerio","image":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/secure.gravatar.com\/avatar\/cb548e4205775273d33308ca72a531966ded49102d271cbad24375f4fb220e19?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/cb548e4205775273d33308ca72a531966ded49102d271cbad24375f4fb220e19?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/cb548e4205775273d33308ca72a531966ded49102d271cbad24375f4fb220e19?s=96&d=mm&r=g","caption":"Luis Valerio"},"url":"https:\/\/omcabogados.com.pe\/en\/author\/luisvalerio\/"}]}},"rttpg_featured_image_url":{"full":["https:\/\/omcabogados.com.pe\/wp-content\/uploads\/omc-abogados-y-consultores-actualidad-de-la-propiedad-intelectual-en-latinoamerica.webp",660,440,false],"landscape":["https:\/\/omcabogados.com.pe\/wp-content\/uploads\/omc-abogados-y-consultores-actualidad-de-la-propiedad-intelectual-en-latinoamerica.webp",660,440,false],"portraits":["https:\/\/omcabogados.com.pe\/wp-content\/uploads\/omc-abogados-y-consultores-actualidad-de-la-propiedad-intelectual-en-latinoamerica.webp",660,440,false],"thumbnail":["https:\/\/omcabogados.com.pe\/wp-content\/uploads\/omc-abogados-y-consultores-actualidad-de-la-propiedad-intelectual-en-latinoamerica-338x170.webp",338,170,true],"medium":["https:\/\/omcabogados.com.pe\/wp-content\/uploads\/omc-abogados-y-consultores-actualidad-de-la-propiedad-intelectual-en-latinoamerica-408x272.webp",408,272,true],"large":["https:\/\/omcabogados.com.pe\/wp-content\/uploads\/omc-abogados-y-consultores-actualidad-de-la-propiedad-intelectual-en-latinoamerica.webp",660,440,false],"1536x1536":["https:\/\/omcabogados.com.pe\/wp-content\/uploads\/omc-abogados-y-consultores-actualidad-de-la-propiedad-intelectual-en-latinoamerica.webp",660,440,false],"2048x2048":["https:\/\/omcabogados.com.pe\/wp-content\/uploads\/omc-abogados-y-consultores-actualidad-de-la-propiedad-intelectual-en-latinoamerica.webp",660,440,false],"trp-custom-language-flag":["https:\/\/omcabogados.com.pe\/wp-content\/uploads\/omc-abogados-y-consultores-actualidad-de-la-propiedad-intelectual-en-latinoamerica-18x12.webp",18,12,true],"gt3theme_mobile":["https:\/\/omcabogados.com.pe\/wp-content\/uploads\/omc-abogados-y-consultores-actualidad-de-la-propiedad-intelectual-en-latinoamerica-480x320.webp",480,320,true],"vp_sm":["https:\/\/omcabogados.com.pe\/wp-content\/uploads\/omc-abogados-y-consultores-actualidad-de-la-propiedad-intelectual-en-latinoamerica-500x333.webp",500,333,true],"vp_md":["https:\/\/omcabogados.com.pe\/wp-content\/uploads\/omc-abogados-y-consultores-actualidad-de-la-propiedad-intelectual-en-latinoamerica.webp",660,440,false],"vp_lg":["https:\/\/omcabogados.com.pe\/wp-content\/uploads\/omc-abogados-y-consultores-actualidad-de-la-propiedad-intelectual-en-latinoamerica.webp",660,440,false],"vp_xl":["https:\/\/omcabogados.com.pe\/wp-content\/uploads\/omc-abogados-y-consultores-actualidad-de-la-propiedad-intelectual-en-latinoamerica.webp",660,440,false],"vp_sm_popup":["https:\/\/omcabogados.com.pe\/wp-content\/uploads\/omc-abogados-y-consultores-actualidad-de-la-propiedad-intelectual-en-latinoamerica-500x333.webp",500,333,true],"vp_md_popup":["https:\/\/omcabogados.com.pe\/wp-content\/uploads\/omc-abogados-y-consultores-actualidad-de-la-propiedad-intelectual-en-latinoamerica.webp",660,440,false],"vp_xl_popup":["https:\/\/omcabogados.com.pe\/wp-content\/uploads\/omc-abogados-y-consultores-actualidad-de-la-propiedad-intelectual-en-latinoamerica.webp",660,440,false]},"rttpg_author":{"display_name":"Luis Valerio","author_link":"https:\/\/omcabogados.com.pe\/en\/author\/luisvalerio\/"},"rttpg_comment":0,"rttpg_category":"<a href=\"https:\/\/omcabogados.com.pe\/en\/category\/prensa\/notas-de-prensa\/\" rel=\"category tag\">Notas de Prensa<\/a>","rttpg_excerpt":"Como especialistas en Propiedad Intelectual en Latinoam\u00e9rica, OMC Abogados &amp; Consultores informa que durante los primeros meses del a\u00f1o se han implementado cambios enfocados en agilizar los procedimientos y reducir los tiempos para tramitar patentes y registrar marcas en la regi\u00f3n. Actualidad de la Propiedad Intelectual en Latinoam\u00e9rica: M\u00e9xico y Argentina anunciaron cambios en sus&hellip;","_links":{"self":[{"href":"https:\/\/omcabogados.com.pe\/en\/wp-json\/wp\/v2\/posts\/16915","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/omcabogados.com.pe\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/omcabogados.com.pe\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/omcabogados.com.pe\/en\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/omcabogados.com.pe\/en\/wp-json\/wp\/v2\/comments?post=16915"}],"version-history":[{"count":12,"href":"https:\/\/omcabogados.com.pe\/en\/wp-json\/wp\/v2\/posts\/16915\/revisions"}],"predecessor-version":[{"id":16938,"href":"https:\/\/omcabogados.com.pe\/en\/wp-json\/wp\/v2\/posts\/16915\/revisions\/16938"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/omcabogados.com.pe\/en\/wp-json\/wp\/v2\/media\/16914"}],"wp:attachment":[{"href":"https:\/\/omcabogados.com.pe\/en\/wp-json\/wp\/v2\/media?parent=16915"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/omcabogados.com.pe\/en\/wp-json\/wp\/v2\/categories?post=16915"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/omcabogados.com.pe\/en\/wp-json\/wp\/v2\/tags?post=16915"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}